{"id":26607,"date":"2019-08-27T16:09:34","date_gmt":"2019-08-27T14:09:34","guid":{"rendered":"https:\/\/magazin.ehorses.de\/?p=26607"},"modified":"2022-05-30T14:29:04","modified_gmt":"2022-05-30T12:29:04","slug":"deckhengst-nabab-de-reve-im-portrait","status":"publish","type":"post","link":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/","title":{"rendered":"Deckhengst Nabab de Reve im Portrait"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<strong>Nabab de Reve war seinerzeit ein sehr erfolgreiches Springpferd, welches sich vor allem nach seiner aktiven Karriere zu einem der bedeutendsten Vererber in der Springpferdezucht erwiesen hat. Neben vielen internationalen Siegen und Platzierungen z\u00e4hlte die Team-Bronzemedaille bei den Weltreiterspielen in Jerez de la Frontera (Spanien) zu seinen gr\u00f6\u00dften Erfolgen.<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Steckbrief<\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pcrstb-wrap\"><table style=\"border-collapse: collapse; width: 100%;\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\">Geboren<\/td>\n<td style=\"width: 50%;\">1990<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Gestorben<\/td>\n<td style=\"width: 50%;\">2015<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Rasse<\/td>\n<td style=\"width: 50%;\"><a href=\"https:\/\/www.ehorses.de\/magazin\/pferderassen\/selle-francais\/\">Selle Francais<\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Farbe<\/td>\n<td style=\"width: 50%;\">Braun<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Verband<\/td>\n<td style=\"width: 50%;\">Selle Francais<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Stockma\u00df<\/td>\n<td style=\"width: 50%;\">173cm<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Z\u00fcchter<\/td>\n<td style=\"width: 50%;\"><span style=\"font-weight: 400;\">Stephan de Bruyn\/Belgien<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Zuchtwert<\/td>\n<td style=\"width: 50%;\">148<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Zuchtsicherheit<\/td>\n<td style=\"width: 50%;\">88%<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 50%;\">Zulassungen<\/td>\n<td style=\"width: 50%;\"><span style=\"font-weight: 400;\">Zugelassen f\u00fcr Selle Francais, <a href=\"https:\/\/www.ehorses.de\/magazin\/pferderassen\/belgisches-warmblut\/\">Belgisches Warmblut<\/a>, <a href=\"https:\/\/www.ehorses.de\/magazin\/pferderassen\/schwedisches-warmblut\/\">Schwedisches Warmblut<\/a>, Holsteiner, Oldenburger<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Leben und Erfolge von Nabab de Reve<\/h2>\n<p>Nabab de Reve war schon als Youngster in Aufbaupr\u00fcfungen erfolgreich, bevor er neunj\u00e4hrig von seinem sp\u00e4teren Erfolgsreiter Philippe Le Jeune \u00fcbernommen wurde. Schon von Beginn an war die Karriere von ihm und Le Jeune von Erfolg gekr\u00f6nt. Zusammen <strong>gewannen<\/strong> sie unz\u00e4hlige <strong>Gro\u00dfe Preise<\/strong>, darunter auch den Nationenpreis mit dem belgischen Team von Aachen im Jahr 2001. Im Jahr darauf sprang der Hengst mit seinem langj\u00e4hrigen Reiter zu Team-Bronze bei den Weltreiterspielen in Jerez de la Frontera. Daraufhin wurde er 2002 zum Pferd des Jahres gew\u00e4hlt.<\/p>\n<p><span style=\"font-weight: 400;\">Seinen verdienten <strong>Ruhestand<\/strong> verbrachte der Hengst im Stal de Muze, wo er auch 2015 verstarb. <\/span><\/p>\n<p><strong>Philippe Le Jeune mit Nabab de Reve in La Baule:<\/strong>[\/vc_column_text][vc_raw_html]JTNDaWZyYW1lJTIwd2lkdGglM0QlMjI1NjAlMjIlMjBoZWlnaHQlM0QlMjIzMTUlMjIlMjBzcmMlM0QlMjJodHRwcyUzQSUyRiUyRnd3dy55b3V0dWJlLW5vY29va2llLmNvbSUyRmVtYmVkJTJGaGEwMnFZZk9veGclMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBhbGxvdyUzRCUyMmFjY2VsZXJvbWV0ZXIlM0IlMjBhdXRvcGxheSUzQiUyMGVuY3J5cHRlZC1tZWRpYSUzQiUyMGd5cm9zY29wZSUzQiUyMHBpY3R1cmUtaW4tcGljdHVyZSUyMiUyMGFsbG93ZnVsbHNjcmVlbiUzRSUzQyUyRmlmcmFtZSUzRQ==[\/vc_raw_html][vc_raw_html]JTNDZGl2JTIwaWQlM0QlRTIlODAlOUNpbmNvbnRlbnRfMSVFMiU4MCU5RCUzRSUzQyUyRmRpdiUzRQ==[\/vc_raw_html][vc_column_text]<\/p>\n<h2>Nachkommen von Nabab de Reve<\/h2>\n<p>Die Liste der Nachkommen von Nabab de Reve im internationalen Springsport ist lang. Er ist sowohl als Vater, als auch als Muttervater immer wieder im Pedigree erfolgreicher Springpferde zu finden. Zu den ber\u00fchmtesten S\u00f6hnen geh\u00f6rt wohl auch Vigo d\u2018Arsouilles, welcher ebenfalls von Philippe Le Jeune geritten wurde. Mit ihm konnte Le Jeune bei den Weltreiterspielen in Kentucky im Jahre 2010 seinen Traum vom Einzelweltmeistertitel wahr machen und gewann dar\u00fcber hinaus noch mit der belgischen Mannschaft Team-Bronze. Auch bei den<strong> Olympischen Spielen 2012<\/strong> in London war ein Nabab de Reve Sohn erfolgreich: Glock\u2018s London (vorher Eurocommerce London) konnte sich unter Gerco Schr\u00f6der die<strong> Silbermedaille im Einzel <\/strong>bei den Springreitern sichern.<\/p>\n<p>Noch beim selben Event warer auch als Muttervater h\u00f6chst erfolgreich, denn der belgische Wallach Hello Sanctos erregte mit seinem Reiter Scott Brash gro\u00dfes Aufsehen, indem er einen wesentlichen Anteil zur olympischen <strong>Mannschafts-Goldmedaille<\/strong> leistete. In seiner weiteren Karriere konnte Scott Brash mit seinem Hello Sanctos, als erster Reiter \u00fcberhaupt, auch den mit 1,3 Millionen Euro dotierten Grand Slam gewinnen. Diese Turnierserie verbindet die vier wichtigsten Springpr\u00fcfungen der Welt. Um den Grand Slam zu gewinnen, m\u00fcssen mindestens drei aufeinanderfolgende Pr\u00fcfungen gewonnen werden.<\/p>\n<p>Generell galt Nabab de Reve als \u201ekalibriges\u201c Pferd, dem eher h\u00f6her im Blut stehende Stuten zugef\u00fchrt wurden, welche flink und wendig waren. Dennoch ist er ein <strong>Linienbegr\u00fcnder der Neuzeit<\/strong>, welcher sich nicht nur selbst im Sport bewiesen hat, sondern dies auch an seine Nachkommen weitergegeben hat.<\/p>\n<p>Auch nach seinem Tod ist der Hengst als erfolgreicher Vererber in unz\u00e4hligen Pedigrees zu finden, sodass er vom WBFSH 2018 unter den <strong>Top 10 der weltweiten Springvererber<\/strong> gerankt wurde.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Stammbaum<\/h2>\n<div class=\"pcrstb-wrap\"><table style=\"border-collapse: collapse; width: 100%; height: 104px;\">\n<tbody>\n<tr style=\"height: 26px;\">\n<td style=\"width: 33.3333%; height: 104px;\" rowspan=\"4\"><strong>Nabab de Reve<\/strong> \u2642<\/td>\n<td style=\"width: 33.3333%; height: 52px;\" rowspan=\"2\"><strong>Quidam de Revel<\/strong> \u2642<br \/>\nSelle Francais<br \/>\nBraun,<br \/>\n1982<\/td>\n<td style=\"width: 33.3333%; height: 26px;\"><strong>Jalisco B<\/strong> \u2642<br \/>\nSelle Francais<br \/>\nBraun,<br \/>\n1975<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 33.3333%; height: 26px;\"><strong>Dirka<\/strong> \u2640<br \/>\nSelle Francais<br \/>\nDunkelbraun,<br \/>\n1969<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 33.3333%; height: 52px;\" rowspan=\"2\"><strong>Melodie en Fa<\/strong> \u2640<br \/>\nSelle Francais<br \/>\nFuchs,<br \/>\n1978<\/td>\n<td style=\"width: 33.3333%; height: 26px;\"><strong>Artichaut<\/strong> \u2642<br \/>\nSelle Francais<br \/>\nFuchs,<br \/>\n1966<\/td>\n<\/tr>\n<tr style=\"height: 26px;\">\n<td style=\"width: 33.3333%; height: 26px;\"><strong>Caravelle<\/strong> \u2640<br \/>\nSelle Francais<br \/>\nFuchs,<br \/>\n1968<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/div>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"[vc_row][vc_column][vc_column_text]Nabab de Reve war seinerzeit ein sehr erfolgreiches Springpferd, welches sich vor allem nach seiner&hellip;","protected":false},"author":10,"featured_media":51604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[34,2],"tags":[],"class_list":["post-26607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deckhengste-sportpferde","category-pferdesport"],"_oembed_6e2261a90c0f61b3f6e5cbf5248ae69a":null,"_oembed_d83ed97665bbfe5cbf2a5acd0571bfe8":null,"_oembed_879340bd3c064234a240bcda2f369c23":null,"_oembed_519616b8842fb308e7a3039c04f55a79":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nabab de Reve: Deckhengst im Portrait | ehorses.de Magazin<\/title>\n<meta name=\"description\" content=\"Nabab de Reve \u27bd Der erfolgreiche Deckhengst im ausf\u00fchrlichen Portrait \u2713 Jetzt mehr erfahren zu Nabab de Reve im ehorses Magazin!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nabab de Reve: Deckhengst im Portrait | ehorses.de Magazin\" \/>\n<meta property=\"og:description\" content=\"Nabab de Reve \u27bd Der erfolgreiche Deckhengst im ausf\u00fchrlichen Portrait \u2713 Jetzt mehr erfahren zu Nabab de Reve im ehorses Magazin!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/\" \/>\n<meta property=\"og:site_name\" content=\"ehorses Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-27T14:09:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-30T12:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/nabab-de-reve-symbolbild-portrait.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"616\" \/>\n\t<meta property=\"og:image:height\" content=\"411\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Felix Ortmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Felix Ortmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/\"},\"author\":{\"name\":\"Felix Ortmann\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#\\\/schema\\\/person\\\/68e708041964814a3a68735dbc78b9a9\"},\"headline\":\"Deckhengst Nabab de Reve im Portrait\",\"datePublished\":\"2019-08-27T14:09:34+00:00\",\"dateModified\":\"2022-05-30T12:29:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/\"},\"wordCount\":639,\"image\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/nabab-de-reve-symbolbild-portrait.jpg\",\"articleSection\":[\"Deckhengste &amp; Sportpferde\",\"Pferdesport\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/\",\"name\":\"Nabab de Reve: Deckhengst im Portrait | ehorses.de Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/nabab-de-reve-symbolbild-portrait.jpg\",\"datePublished\":\"2019-08-27T14:09:34+00:00\",\"dateModified\":\"2022-05-30T12:29:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#\\\/schema\\\/person\\\/68e708041964814a3a68735dbc78b9a9\"},\"description\":\"Nabab de Reve \u27bd Der erfolgreiche Deckhengst im ausf\u00fchrlichen Portrait \u2713 Jetzt mehr erfahren zu Nabab de Reve im ehorses Magazin!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/nabab-de-reve-symbolbild-portrait.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/nabab-de-reve-symbolbild-portrait.jpg\",\"width\":616,\"height\":411,\"caption\":\"Nabab de Reve im Portrait\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/deckhengst-nabab-de-reve-im-portrait\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deckhengst Nabab de Reve im Portrait\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/\",\"name\":\"ehorses Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#\\\/schema\\\/person\\\/68e708041964814a3a68735dbc78b9a9\",\"name\":\"Felix Ortmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/felix-96x96.png\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/felix-96x96.png\",\"contentUrl\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/felix-96x96.png\",\"caption\":\"Felix Ortmann\"},\"description\":\"Felix arbeitet als Kundenmanager bei ehorses und edogs. Er versorgt Dich zudem mit interessanten Beitr\u00e4gen rund um Pferde. Erreichen kannst Du Felix unter f.ortmann@edogs.de.\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/author\\\/felix-ortmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nabab de Reve: Deckhengst im Portrait | ehorses.de Magazin","description":"Nabab de Reve \u27bd Der erfolgreiche Deckhengst im ausf\u00fchrlichen Portrait \u2713 Jetzt mehr erfahren zu Nabab de Reve im ehorses Magazin!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/","og_locale":"de_DE","og_type":"article","og_title":"Nabab de Reve: Deckhengst im Portrait | ehorses.de Magazin","og_description":"Nabab de Reve \u27bd Der erfolgreiche Deckhengst im ausf\u00fchrlichen Portrait \u2713 Jetzt mehr erfahren zu Nabab de Reve im ehorses Magazin!","og_url":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/","og_site_name":"ehorses Magazin","article_published_time":"2019-08-27T14:09:34+00:00","article_modified_time":"2022-05-30T12:29:04+00:00","og_image":[{"width":616,"height":411,"url":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/nabab-de-reve-symbolbild-portrait.jpg","type":"image\/jpeg"}],"author":"Felix Ortmann","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Felix Ortmann","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#article","isPartOf":{"@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/"},"author":{"name":"Felix Ortmann","@id":"https:\/\/www.ehorses.de\/magazin\/#\/schema\/person\/68e708041964814a3a68735dbc78b9a9"},"headline":"Deckhengst Nabab de Reve im Portrait","datePublished":"2019-08-27T14:09:34+00:00","dateModified":"2022-05-30T12:29:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/"},"wordCount":639,"image":{"@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/nabab-de-reve-symbolbild-portrait.jpg","articleSection":["Deckhengste &amp; Sportpferde","Pferdesport"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/","url":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/","name":"Nabab de Reve: Deckhengst im Portrait | ehorses.de Magazin","isPartOf":{"@id":"https:\/\/www.ehorses.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#primaryimage"},"image":{"@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/nabab-de-reve-symbolbild-portrait.jpg","datePublished":"2019-08-27T14:09:34+00:00","dateModified":"2022-05-30T12:29:04+00:00","author":{"@id":"https:\/\/www.ehorses.de\/magazin\/#\/schema\/person\/68e708041964814a3a68735dbc78b9a9"},"description":"Nabab de Reve \u27bd Der erfolgreiche Deckhengst im ausf\u00fchrlichen Portrait \u2713 Jetzt mehr erfahren zu Nabab de Reve im ehorses Magazin!","breadcrumb":{"@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#primaryimage","url":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/nabab-de-reve-symbolbild-portrait.jpg","contentUrl":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/nabab-de-reve-symbolbild-portrait.jpg","width":616,"height":411,"caption":"Nabab de Reve im Portrait"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ehorses.de\/magazin\/deckhengst-nabab-de-reve-im-portrait\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ehorses.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Deckhengst Nabab de Reve im Portrait"}]},{"@type":"WebSite","@id":"https:\/\/www.ehorses.de\/magazin\/#website","url":"https:\/\/www.ehorses.de\/magazin\/","name":"ehorses Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ehorses.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.ehorses.de\/magazin\/#\/schema\/person\/68e708041964814a3a68735dbc78b9a9","name":"Felix Ortmann","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/felix-96x96.png","url":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/felix-96x96.png","contentUrl":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/felix-96x96.png","caption":"Felix Ortmann"},"description":"Felix arbeitet als Kundenmanager bei ehorses und edogs. Er versorgt Dich zudem mit interessanten Beitr\u00e4gen rund um Pferde. Erreichen kannst Du Felix unter f.ortmann@edogs.de.","url":"https:\/\/www.ehorses.de\/magazin\/author\/felix-ortmann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/posts\/26607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/comments?post=26607"}],"version-history":[{"count":0,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/posts\/26607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/media\/51604"}],"wp:attachment":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/media?parent=26607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/categories?post=26607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/tags?post=26607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}