{"id":75248,"date":"2025-05-19T08:08:02","date_gmt":"2025-05-19T06:08:02","guid":{"rendered":"https:\/\/www.ehorses.de\/magazin\/?post_type=produkttest&#038;p=75248"},"modified":"2025-06-10T16:33:30","modified_gmt":"2025-06-10T14:33:30","slug":"erfahrungen-mit-den-produkten-von-lemieux","status":"publish","type":"produkttest","link":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/","title":{"rendered":"Erfahrungen mit den Produkten von LeMieux"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"75248\" class=\"elementor elementor-75248\" data-elementor-post-type=\"produkttest\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-6ee635e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ee635e3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-252e9334\" data-id=\"252e9334\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38c6a2c6 elementor-widget elementor-widget-spacer\" data-id=\"38c6a2c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bf10a84 elementor-widget elementor-widget-text-editor\" data-id=\"2bf10a84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Anzeige: Unsere Produkttester haben \u00fcber mehrere Wochen die Fleece Edges Mesh Brushing Boots und die Suede Dressurschabracke von LeMieux mit ihren Pferden getestet.<\/strong><\/p><p>Wie diese Produkte im Langzeittest abschneiden, kannst du jetzt hier nachlesen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-771be339 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"771be339\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12eda335\" data-id=\"12eda335\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b51d940 elementor-widget elementor-widget-penci-media-carousel\" data-id=\"4b51d940\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_per_view_tablet&quot;:&quot;2&quot;,&quot;slides_per_view_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"penci-media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"penci-block-vc penci-media-carousels pc-ctpos-below\">\n            <div class=\"penci-advanced-carousel-mg\">\n                <div class=\"penci-block_content penci-owl-carousel swiper penci-advanced-carousel penci-owl-carousel-slider\"  data-auto=\"true\" data-autotime=\"4000\" data-speed=\"800\" data-ceffect=\"default\" data-seffect=\"creative\" data-item=\"3\" data-desktop=\"3\"  data-tablet=\"2\" data-tabsmall=\"2\" data-mobile=\"1\">\n                    <div class=\"swiper-wrapper\">\n\t\t\t\t\t\t                            <div class=\"swiper-slide penci-media-item elementor-repeater-item-933e003\">\n                                <div class=\"penci-media-inner\">\n                                    <div class=\"penci-media-inct\">\n                                        <div class=\"penci-media-img\">\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"pc-adcr-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152820-1-scaled.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t                            <div class=\"swiper-slide penci-media-item elementor-repeater-item-c968b71\">\n                                <div class=\"penci-media-inner\">\n                                    <div class=\"penci-media-inct\">\n                                        <div class=\"penci-media-img\">\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"pc-adcr-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image0-25-1-scaled.jpeg\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t                            <div class=\"swiper-slide penci-media-item elementor-repeater-item-7ec2afc\">\n                                <div class=\"penci-media-inner\">\n                                    <div class=\"penci-media-inct\">\n                                        <div class=\"penci-media-img\">\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"pc-adcr-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7386-1-scaled.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t                            <div class=\"swiper-slide penci-media-item elementor-repeater-item-14eef49\">\n                                <div class=\"penci-media-inner\">\n                                    <div class=\"penci-media-inct\">\n                                        <div class=\"penci-media-img\">\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"pc-adcr-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image1-24-rotated.jpeg\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t                            <div class=\"swiper-slide penci-media-item elementor-repeater-item-a13abcf\">\n                                <div class=\"penci-media-inner\">\n                                    <div class=\"penci-media-inct\">\n                                        <div class=\"penci-media-img\">\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"pc-adcr-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image3-12-1-scaled.jpeg\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t                            <div class=\"swiper-slide penci-media-item elementor-repeater-item-a50a233\">\n                                <div class=\"penci-media-inner\">\n                                    <div class=\"penci-media-inct\">\n                                        <div class=\"penci-media-img\">\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"pc-adcr-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t                                            <div class=\"penci-image-holder penci-lazy\" data-bgset=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7359-1-scaled.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t                                            <\/div>\n                                        <\/div>\n\t\t\t\t\t\t\t\t\t\t                                    <\/div>\n                                <\/div>\n                            <\/div>\n\t\t\t\t\t\t\t                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-713030cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"713030cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-78e470bb\" data-id=\"78e470bb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5160ce7 elementor-widget elementor-widget-spacer\" data-id=\"5160ce7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-3e78fe31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e78fe31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2490369c\" data-id=\"2490369c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68f09781 elementor-widget elementor-widget-heading\" data-id=\"68f09781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erfahrungsberichte: Fleece Edged Mesh Brushing Boots<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-1d44919e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1d44919e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a61a719\" data-id=\"7a61a719\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b48f751 elementor-widget elementor-widget-accordion\" data-id=\"7b48f751\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2061\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2061\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Cindy<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2061\"><p>Ich habe die <strong>Gamaschen<\/strong> nun seit vier Wochen im Einsatz und bin <strong>absolut zufrieden<\/strong>! Mein dreij\u00e4hriger Wallach l\u00e4uft damit sehr gut, sie sitzen perfekt und bieten ihm die n\u00f6tige <strong>Unterst\u00fctzung<\/strong>, ohne ihn in seiner Bewegung einzuschr\u00e4nken. Besonders <strong>positiv<\/strong> f\u00e4llt mir auf, dass er darunter nicht schwitzt, selbst bei l\u00e4ngeren <strong>Trainingseinheiten<\/strong> oder w\u00e4rmeren Temperaturen. Das war mir besonders wichtig, da ich verhindern m\u00f6chte, dass sich unter den Gamaschen <strong>Hitzestau<\/strong> oder <strong>unangenehme Reibung<\/strong> bildet.<br \/>Die Verarbeitung ist wirklich hochwertig \u2013 die N\u00e4hte sind sauber verarbeitet, das Material f\u00fchlt sich robust, aber gleichzeitig angenehm weich an, und die Klettverschl\u00fcsse halten sicher, ohne sich w\u00e4hrend des Reitens oder im Gel\u00e4nde zu l\u00f6sen. Das <strong>Anlegen<\/strong> und <strong>Abnehmen<\/strong> der Gamaschen ist super einfach, was mir den Alltag enorm erleichtert. Ich habe sie sowohl beim Training auf dem Platz als auch bei Ausritten getestet, und sie bieten durchweg einen <strong>tollen Schutz<\/strong>.<\/p><p>Zus\u00e4tzlich lassen sie sich sehr <strong>gut reinigen<\/strong> \u2013 Schmutz und Staub lassen sich einfach abwischen, und auch nach mehreren Eins\u00e4tzen sehen sie noch aus wie neu. Alles in allem bin ich wirklich <strong>begeistert<\/strong>! Ich kann die Gamaschen auf jeden Fall <strong>weiterempfehlen<\/strong>, da sie nicht nur funktional und sch\u00fctzend sind, sondern auch durch ihre <strong>Qualit\u00e4t<\/strong> und <strong>Trageeigenschaften<\/strong> absolut \u00fcberzeugen!<\/p><div data-sliderid=\"33376\" id=\"penci-post-gallery__33376\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image0-27-rotated.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image0-27-rotated.jpeg\" alt=\"\" title=\"image0 (27)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image1-24-rotated.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image1-24-rotated.jpeg\" alt=\"\" title=\"image1 (24)\"><\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2062\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2062\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Vanessa<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2062\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2062\"><p>Dank ehorses hatten wir wieder die M\u00f6glichkeit, ein weiteres tolles Produkt testen zu d\u00fcrfen. Diesmal waren es die neuen <strong>LeMieux Fleece Edge Mesh Boots<\/strong>, ganz klassisch in Schwarz.<\/p><p>Seit einiger Zeit reite ich meine Pferde zu Hause in der dressurm\u00e4\u00dfigen Arbeit sehr gerne mit solchen Arbeitsgamaschen. Daher war ich sehr, sehr neugierig, denn von <strong>LeMieux<\/strong> wurde ich bis jetzt noch nie entt\u00e4uscht.<\/p><p>Schon der erste Eindruck beim Auspacken war <strong>vielversprechend<\/strong> \u2013 eine gelungene Kombination aus tollem Design, Komfort und hoher Luftdurchl\u00e4ssigkeit. Die Gamaschen f\u00fchlen sich super flauschig und sehr leicht an. Betrachtet man das Innenfutter genauer, bemerkt man den luftdurchl\u00e4ssigen Stoff und die <strong>hochwertige Verarbeitung<\/strong>. So bleiben die Beine auch nach einem anstrengenden Training trocken und bestens bel\u00fcftet.<\/p><p>Im Vergleich zu meinen anderen <strong>Dressurgamaschen<\/strong> sind sie deutlich leichter. Durch das flauschige Fleece entstehen so gut wie keine Scheuerstellen \u2013 selbst wenn der Boden einmal etwas weicher ist und Schmutz an die Gamaschen kommt. Eine ideale Alternative also f\u00fcr Pferde, die \u2013 wie <strong>Nino<\/strong> \u2013 sehr sensibel am R\u00f6hrbein reagieren. In diesem Fall ist die <strong>Mesh-Fleece-Kombination<\/strong> einfach perfekt.<\/p><p>Dank der zwei Riemen (wobei der obere deutlich breiter ist) sitzt die Gamasche <strong>bombenfest<\/strong> am Pferdebein. Ein l\u00e4stiges Verrutschen gab es kein einziges Mal, selbst wenn gelegentlich daran gerieben wurde. Durch den breiteren Riemen entsteht zudem<strong> kein unangenehmer Druck<\/strong> auf das Bein, und ich hatte nie Bedenken, ob ich die Gamaschen zu fest angezogen habe. Auch mit Handschuhen lassen sich die Riemen problemlos \u00f6ffnen und schlie\u00dfen.<\/p><p>Der sehr robuste <strong>PU-Ledereinsatz<\/strong> h\u00e4lt Schl\u00e4gen und dem Zusammensto\u00dfen der Beine gut stand, ohne dabei zu starr oder zu fest zu sein.<\/p><p>Zun\u00e4chst hatte ich etwas Bedenken, ob es die richtige Gr\u00f6\u00dfe ist \u2013 sie kamen mir etwas klein vor, und <strong>Nino<\/strong> tr\u00e4gt normalerweise <strong>L<\/strong>. Doch sie passen wie <strong>angegossen<\/strong> und schmiegen sich perfekt um das Pferdebein.<\/p><p>Nach der vierw\u00f6chigen Testphase stand nat\u00fcrlich auch der ultimative H\u00e4rtetest an \u2013 die <strong>Waschmaschine<\/strong>.<br \/>Alle meine Gamaschen und allgemein meine Reitsachen m\u00fcssen leicht zu reinigen sein. Wir reiten oft drau\u00dfen, auch bei weniger sch\u00f6nem Wetter, und ich hasse es, wenn man die Sachen nur mit der Hand putzen kann und sie danach trotzdem noch schmutzig aussehen. Also ab in die Maschine bei 30 Grad \u2013 und das Ergebnis war <strong>sensationell<\/strong>! Das Fleece blieb genau dort, wo es hingeh\u00f6rt, das Innenfutter war wieder sauber, die Klettverschl\u00fcsse genauso stark wie vorher \u2013 genau so liebe ich es. Einmal trocknen lassen und am n\u00e4chsten Tag waren sie schon wieder <strong>einsatzbereit<\/strong>.<\/p><p><strong>Mein Fazit nach der Testphase:<\/strong> <strong>LeMieux<\/strong> hat mich wieder einmal nicht entt\u00e4uscht! Diese Gamaschen sind inzwischen ein fester Bestandteil meiner t\u00e4glichen Arbeit \u2013 und man sieht es ihnen nicht einmal an. Qualit\u00e4t, Verarbeitung und Material \u00fcberzeugen zu 100 Prozent.<\/p><p>Ich kann sie wirklich jedem ans Herz legen, der sich in naher Zukunft neue Arbeitsgamaschen zulegen m\u00f6chte!<\/p><div data-sliderid=\"69756\" id=\"penci-post-gallery__69756\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152535-1-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152535-1-585x780.jpg\" alt=\"\" title=\"20250130_152535 (1)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152617-1-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152617-1-585x439.jpg\" alt=\"\" title=\"20250130_152617 (1)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152712-1-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/20250130_152712-1-585x780.jpg\" alt=\"\" title=\"20250130_152712 (1)\"><\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-19a2e89d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19a2e89d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a3078e5\" data-id=\"7a3078e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-0b0e0a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b0e0a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-523e8a8\" data-id=\"523e8a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5612b78 elementor-widget elementor-widget-heading\" data-id=\"5612b78\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erfahrungsberichte: Suede Dressurschabracke<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-67daadf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67daadf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4361524\" data-id=\"4361524\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8faa6d0 elementor-widget elementor-widget-accordion\" data-id=\"8faa6d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1501\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1501\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Linda<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1501\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1501\"><p>Seit einigen Wochen durfte ich eine <strong>Suede Dressurschabracke<\/strong> <strong>von LeMieux<\/strong> testen. Optisch wirkt sie <strong>hochwertig<\/strong> verarbeitet. Die Oberfl\u00e4che besteht aus <strong>Wildleder<\/strong> und f\u00fchlt sich sehr, sehr weich an.<\/p><p>Unter dem Sattel zeigt die Schabracke eine <strong>super Passform<\/strong>, und auch auf meinem Pony passt die Gr\u00f6\u00dfe Warmblut. Besonders gut gef\u00e4llt mir der eingen\u00e4hte Schutz im Sattelgurtbereich. Da mein Pony in diesem Bereich empfindlich ist und leicht zu Scheuerstellen neigt, bietet die Schabracke hier zus\u00e4tzlichen <strong>Schutz<\/strong>.<\/p><p>Meiner Meinung nach <strong>trocknet<\/strong> sie <strong>schneller<\/strong> als andere Schabracken. Nach einem Training ist es kein Problem, sie am n\u00e4chsten Tag wieder zu verwenden.<\/p><p>Auch nach dem <strong>Waschen<\/strong> sieht die Schabracke aus wie neu \u2013 sie ist weder eingelaufen noch verzogen oder verf\u00e4rbt.<\/p><p>Insgesamt l\u00e4sst sich sagen, dass das <strong>Preis-Leistungs-Verh\u00e4ltnis<\/strong> wirklich super ist und man f\u00fcr den Preis eine sehr <strong>hochwertige Suede Dressurschabracke <\/strong>erh\u00e4lt.<\/p><div data-sliderid=\"82224\" id=\"penci-post-gallery__82224\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image3-12-1-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image3-12-1-585x780.jpeg\" alt=\"\" title=\"image3 (12) (1)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image2-14-1-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image2-14-1-585x780.jpeg\" alt=\"\" title=\"image2 (14) (1)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image1-22-1-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image1-22-1-585x780.jpeg\" alt=\"\" title=\"image1 (22) (1)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image0-25-1-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/image0-25-1-585x780.jpeg\" alt=\"\" title=\"image0 (25) (1)\"><\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1502\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1502\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Lisa<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1502\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1502\"><p>Zwei Wochen hatte ich nun Zeit, die Suede Dressurschabracke von LeMieux in der Farbe Ice Blue zu testen.<\/p><p>Bereits beim ersten Anfassen f\u00e4llt das angenehm weiche Obermaterial aus <strong>Baumwolle<\/strong> positiv auf. Dazu ist sie durch die Bambusf\u00fctterung <strong>atmungsaktiv<\/strong>, was gerade bei intensiveren Trainingseinheiten f\u00fcr ein optimales Klima unter dem Sattel sorgt. Der Schwei\u00df wird gut aufgenommen, und es gibt keine Scheuerstellen. Nach dem Training trocknet das Material schnell wieder ab.<\/p><p>Die <strong>Passform<\/strong> ist sehr gut. Besonders hervorzuheben ist die hohe Widerristaussparung, die eine ideale Positionierung auf dem Pferder\u00fccken erm\u00f6glicht. Sie verf\u00fcgt au\u00dferdem \u00fcber elastische D-Ring-Laschen. Egal ob im Gel\u00e4nde oder bei anspruchsvolleren Lektionen \u2013 die Suede Dressurschabracke bleibt an Ort und Stelle, kein Verrutschen.<\/p><p>Ein weiteres Highlight ist f\u00fcr mich der Gurtbereich. Dieser ist durch <strong>PU-Leder<\/strong> verst\u00e4rkt und verhindert so ebenfalls ein Hochrutschen, z. B. beim Nachgurten. Das Gurtband erm\u00f6glicht es, die Gurtstrippen einzeln in darunterliegende, kleinere, abgetrennte Gurtb\u00e4nder zu ziehen und sorgt somit auch daf\u00fcr, dass ein seitliches Verrutschen nicht mehr m\u00f6glich ist.<\/p><p>Auch <strong>optisch<\/strong> \u00fcberzeugt mich das Modell auf ganzer Linie. Die Farbe ist ein echter Blickfang. Die <strong>hochwertige<\/strong> Verarbeitung mit stabilen N\u00e4hten, fein abgestimmten Details und einem eleganten Logo rundet den sch\u00f6nen Gesamteindruck ab.<\/p><p><strong>Fazit<\/strong>: Es ist ein durch und durch gelungenes Produkt. Die Suede Dressurschabracke hat mich mit einer Kombination aus Funktionalit\u00e4t, Tragekomfort und Design wirklich \u00fcberzeugt.<\/p><div data-sliderid=\"37420\" id=\"penci-post-gallery__37420\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Schabracke3-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Schabracke3-585x1043.jpg\" alt=\"\" title=\"Schabracke3\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Schabracke1-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Schabracke1-585x440.jpg\" alt=\"\" title=\"Schabracke1\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Logo-3-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Logo-3-585x777.jpg\" alt=\"\" title=\"Logo\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Schabracke4-scaled.jpg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Schabracke4-585x518.jpg\" alt=\"\" title=\"Schabracke4\"><\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1503\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1503\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Nicole<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1503\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1503\"><p class=\"\" data-start=\"100\" data-end=\"342\">Ich durfte die LeMieux Suede Dressage Square Dressurschabracke auf meiner sensiblen Stute Daggy testen, die bekannterma\u00dfen schnell schwitzt und aktuell auch noch ein ordentliches Winterfell mit sich herumtr\u00e4gt \u2013 perfekte Testbedingungen also.<\/p><p class=\"\" data-start=\"344\" data-end=\"808\"><strong data-start=\"344\" data-end=\"365\">Design &amp; Material<\/strong><br data-start=\"365\" data-end=\"368\" \/>Die Farbe Ice Blue ist einfach ein Traum \u2013 frisch, elegant und richtig sch\u00f6n kombinierbar mit anderen Accessoires aus dem Sortiment (z. B. passender Fliegenhaube). Daggy ist ein Fuchs \u2013 unsere Auswahl an Farben ist demnach nicht gro\u00df, und dieses Blau ist einfach ein Match.<br data-start=\"641\" data-end=\"644\" \/>Die Oberfl\u00e4che aus weichem Suede f\u00fchlt sich luxuri\u00f6s an und sieht zudem absolut hochwertig aus \u2013 ohne diesen typischen Satin-Glanz, den ich pers\u00f6nlich nicht so mag.<\/p><p class=\"\" data-start=\"810\" data-end=\"1119\">Die Suede Dressurschabracke kommt mit einem PU-Leder-Gurtschutz, der nicht nur optisch etwas hermacht, sondern auch praktisch ist. Er sch\u00fctzt das Material vor Abnutzung, und man l\u00e4uft nicht Gefahr, die Schabracke in Falten zu legen und f\u00fcr Reibung am Pferd zu sorgen. Es wird au\u00dferdem verhindert, dass der Gurt wegrutscht.<\/p><p class=\"\" data-start=\"1121\" data-end=\"2058\"><strong data-start=\"1121\" data-end=\"1144\">Passform &amp; Funktion<\/strong><br data-start=\"1144\" data-end=\"1147\" \/>Die Passform ist f\u00fcr mich das herausragende Merkmal: hoher Widerrist, super Schnitt, liegt ruhig und satt \u2013 selbst bei einem bewegungsstarken Pferd wie Daggy. Die elastischen D-Ring-Laschen sorgen f\u00fcr zus\u00e4tzliche Stabilit\u00e4t, aber auch Flexibilit\u00e4t \u2013 f\u00fcr mich ein Novum. Der Sattel bleibt, wo er hingeh\u00f6rt, und die Suede Dressurschabracke auch.<br data-start=\"1477\" data-end=\"1480\" \/>Das Innenfutter aus Bambus (60 % Viskose aus der Bambusfaser, 40 % Polyester) ist besonders weich und sorgt f\u00fcr eine optimale Schwei\u00dfabsorption. Trotz des dichten Fells und der Schwitzneigung hatte ich nie das Gef\u00fchl, dass die Hitze sich staut \u2013 die Feuchtigkeit wurde gut abgeleitet.<br data-start=\"1764\" data-end=\"1767\" \/>Die Suede Dressurschabracke ist maschinenwaschbar, und das m\u00fcssen Schabracken f\u00fcr mich auch sein (ich habe daf\u00fcr einen gro\u00dfen Waschbeutel). Sie verliert dabei nicht an Form und Stabilit\u00e4t. Man kann sie kurz in Form zupfen, sollte sie sich doch in Falten gelegt haben; bei mir war das aber nicht der Fall.<\/p><p class=\"\" data-start=\"2060\" data-end=\"2292\"><strong data-start=\"2060\" data-end=\"2069\">Fazit<\/strong><br data-start=\"2069\" data-end=\"2072\" \/>Die LeMieux Suede Dressage Square \u00fcberzeugt mich rundum \u2013 sie kombiniert hochwertige Materialien, edles Design und eine absolut durchdachte Passform. F\u00fcr mich und Daggy definitiv ein neues Lieblingsst\u00fcck im Stall.<\/p><div data-sliderid=\"23542\" id=\"penci-post-gallery__23542\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_0338-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_0338-585x780.jpeg\" alt=\"\" title=\"IMG_0338\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_0764-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_0764-585x780.jpeg\" alt=\"\" title=\"IMG_0764\"><\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bae361a elementor-widget elementor-widget-accordion\" data-id=\"bae361a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1951\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1951\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Marie von ehorses testet beide Produkte<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1951\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1951\"><p class=\"\" data-start=\"85\" data-end=\"580\">Ich durfte sowohl die <strong>Gamaschen<\/strong> als auch die <strong>Suede Dressurschabracke von LeMieux<\/strong> testen und bin wirklich begeistert von beiden Produkten. Die Schabracke hat mich besonders durch ihre perfekte Passform \u00fcberzeugt. Sie liegt ruhig und sicher auf dem R\u00fccken meines Pferdes, ohne zu verrutschen, und die <strong>atmungsaktive<\/strong> <strong>Bambusf\u00fctterung<\/strong> sorgt f\u00fcr ein ideales Klima unter dem Sattel \u2013 selbst bei l\u00e4ngeren Trainingseinheiten. Die Farbe Ice Blue ist ein zus\u00e4tzlicher <strong>Pluspunkt<\/strong>, sie sieht einfach toll aus!<\/p><p class=\"\" data-start=\"582\" data-end=\"974\">Was die Gamaschen betrifft, bin ich ebenfalls sehr zufrieden. Sie bieten <strong>exzellenten<\/strong> <strong>Schutz<\/strong>, ohne dass mein Pferd sich eingeengt f\u00fchlt. Die elastischen Riemen sorgen f\u00fcr einen <strong>sicheren<\/strong> <strong>Halt<\/strong>, und das weiche Fleece verhindert, dass Reibung entsteht. Besonders praktisch finde ich den robusten <strong>PU-Leder-Schlagpolster<\/strong>, der vor St\u00f6\u00dfen sch\u00fctzt und gleichzeitig die Gamaschen sehr langlebig macht.<\/p><p class=\"\" data-start=\"976\" data-end=\"1278\">Beide Produkte sind nicht nur funktional, sondern auch optisch ein Hingucker \u2013 die <strong>Qualit\u00e4t<\/strong> und Verarbeitung sind wirklich top.\u00a0 Ich kann die Suede Dressurschabracke und die Gamaschen von LeMieux definitiv <strong>weiterempfehlen<\/strong>!<\/p><div data-sliderid=\"98437\" id=\"penci-post-gallery__98437\" class=\"penci-post-gallery-container justified column-3\" data-height=\"150\" data-margin=\"3\"><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7349-scaled.png\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7349-585x780.png\" alt=\"\" title=\"IMG_7349\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7326-scaled.png\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7326-585x780.png\" alt=\"\" title=\"IMG_7326\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7303-scaled.png\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7303-585x780.png\" alt=\"\" title=\"IMG_7303\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7386-1-scaled.png\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7386-1-585x780.png\" alt=\"\" title=\"IMG_7386 (1)\"><\/a><a class=\"penci-gallery-ite item-gallery-justified\" href=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7359-1-scaled.png\"><img decoding=\"async\" src=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/IMG_7359-1-585x780.png\" alt=\"\" title=\"IMG_7359 (1)\"><\/a><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-ae06e4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae06e4e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0494f0b\" data-id=\"0494f0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-584196ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"584196ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-148793d1\" data-id=\"148793d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-217c1704 elementor-widget elementor-widget-text-editor\" data-id=\"217c1704\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2><strong>Informationen zu den beiden Produkten von LeMieux:<\/strong><\/h2><p class=\"\" data-start=\"40\" data-end=\"283\"><strong>Fleece Edged Mesh Brushing Boots:<\/strong> Leichte, atmungsaktive Gamaschen von LeMieux \u2013 idealer Schutz f\u00fcr empfindliche Pferdebeine. Robustes PU-Leder, weiches Fleece und elastische Riemen sorgen f\u00fcr Komfort, sicheren Sitz und einfaches Handling. Geeignet f\u00fcr Vorder- und Hinterbeine.<\/p><p><strong>Suede Dressurschabracke:<\/strong> Die Suede Dressurschabracke von LeMieux vereint edles Design mit hoher Funktionalit\u00e4t. Sie unterst\u00fctzt Dein Pferd durch optimale Passform, hohe Atmungsaktivit\u00e4t und angenehmen Tragekomfort \u2013 ideal f\u00fcr Training, Turnier oder Gel\u00e4nderitt.<\/p><h2><strong>Fazit <\/strong><\/h2><p>Die Feedbacks zu den beiden Produkten sind durchweg positiv! Die Besitzer und Besitzerinnen loben vor allem Qualit\u00e4t, Passform und Verarbeitung \u2013 und das Beste: Beide Produkte sind in mehreren Farben erh\u00e4ltlich!<\/p><p><strong>M\u00f6chtest du dir selbst einen Eindruck verschaffen?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-255a50e8 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"255a50e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lemieux.com\/de\/pferd\/beinschutz-bandagen\/fleece-edge-mesh-brushing-boots-black-natural#selection.color=6871\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Infos zu den Gamaschen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f454dee elementor-align-left elementor-widget elementor-widget-button\" data-id=\"f454dee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.lemieux.com\/de\/schabracken\/ice-blue\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Infos zu der Suede Dressurschabracke<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-39d08077 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39d08077\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-553cfae6\" data-id=\"553cfae6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"penci-section penci-disSticky penci-structure-10 elementor-section elementor-top-section elementor-element elementor-element-538905b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"538905b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"penci-ercol-100 penci-ercol-order-1 penci-sticky-ct    elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f17711\" data-id=\"3f17711\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24fe9d2 elementor-widget elementor-widget-spacer\" data-id=\"24fe9d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anzeige: Unsere Produkttester haben \u00fcber mehrere Wochen die Fleece Edges Mesh Brushing Boots und die&hellip;<\/p>\n","protected":false},"author":146,"featured_media":77077,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[40,42],"tags":[],"class_list":["post-75248","produkttest","type-produkttest","status-publish","format-standard","has-post-thumbnail","hentry","category-testergebnisse","category-produkttests"],"_oembed_6e2261a90c0f61b3f6e5cbf5248ae69a":null,"_oembed_d83ed97665bbfe5cbf2a5acd0571bfe8":null,"_oembed_879340bd3c064234a240bcda2f369c23":null,"_oembed_519616b8842fb308e7a3039c04f55a79":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erfahrungen mit den Produkten von LeMieux - ehorses Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erfahrungen mit den Produkten von LeMieux - ehorses Magazin\" \/>\n<meta property=\"og:description\" content=\"Anzeige: Unsere Produkttester haben \u00fcber mehrere Wochen die Fleece Edges Mesh Brushing Boots und die&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/\" \/>\n<meta property=\"og:site_name\" content=\"ehorses Magazin\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T14:33:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"14\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/\",\"name\":\"Erfahrungen mit den Produkten von LeMieux - ehorses Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg\",\"datePublished\":\"2025-05-19T06:08:02+00:00\",\"dateModified\":\"2025-06-10T14:33:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/wp-content\\\/uploads\\\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg\",\"width\":800,\"height\":520,\"caption\":\"Gamaschen und Schabracke von LeMieux\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/produkttest\\\/erfahrungen-mit-den-produkten-von-lemieux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erfahrungen mit den Produkten von LeMieux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/\",\"name\":\"ehorses Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ehorses.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erfahrungen mit den Produkten von LeMieux - ehorses Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/","og_locale":"de_DE","og_type":"article","og_title":"Erfahrungen mit den Produkten von LeMieux - ehorses Magazin","og_description":"Anzeige: Unsere Produkttester haben \u00fcber mehrere Wochen die Fleece Edges Mesh Brushing Boots und die&hellip;","og_url":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/","og_site_name":"ehorses Magazin","article_modified_time":"2025-06-10T14:33:30+00:00","og_image":[{"width":800,"height":520,"url":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"14\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/","url":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/","name":"Erfahrungen mit den Produkten von LeMieux - ehorses Magazin","isPartOf":{"@id":"https:\/\/www.ehorses.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/#primaryimage"},"image":{"@id":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg","datePublished":"2025-05-19T06:08:02+00:00","dateModified":"2025-06-10T14:33:30+00:00","breadcrumb":{"@id":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/#primaryimage","url":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg","contentUrl":"https:\/\/www.ehorses.de\/magazin\/wp-content\/uploads\/Bewerbung-Produkttest-Feedback-PetTec-Sicherheitskamera-800-x-520-px-2.jpg","width":800,"height":520,"caption":"Gamaschen und Schabracke von LeMieux"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ehorses.de\/magazin\/produkttest\/erfahrungen-mit-den-produkten-von-lemieux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.ehorses.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Erfahrungen mit den Produkten von LeMieux"}]},{"@type":"WebSite","@id":"https:\/\/www.ehorses.de\/magazin\/#website","url":"https:\/\/www.ehorses.de\/magazin\/","name":"ehorses Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ehorses.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/produkttest\/75248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/produkttest"}],"about":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/types\/produkttest"}],"author":[{"embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/users\/146"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/comments?post=75248"}],"version-history":[{"count":0,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/produkttest\/75248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/media\/77077"}],"wp:attachment":[{"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/media?parent=75248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/categories?post=75248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ehorses.de\/magazin\/wp-json\/wp\/v2\/tags?post=75248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}